{"id":21735,"date":"2023-02-13T12:28:09","date_gmt":"2023-02-13T12:28:09","guid":{"rendered":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/?page_id=21735"},"modified":"2024-03-08T11:35:57","modified_gmt":"2024-03-08T10:35:57","slug":"terms-and-conditions","status":"publish","type":"page","link":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/terms-and-conditions\/","title":{"rendered":"Terms (new)"},"content":{"rendered":"\n<section class=\"block block-cta-hero \">\n\t<div class=\"uk-flex uk-justify-sb\">\n\t\t<div class=\"hero-content\">\n\t\t\t\t\t\t<h1>Terms and Conditions for FranklinCovey Benelux<\/h1>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"hero-image\">\n\t\t\t<img\n\t\t\t\tsrc=\"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/wp-content\/themes\/franklincovey\/img\/blank.gif\"\n\t\t\t\tdata-src=\"<br \/>\n<b>Warning<\/b>:  Trying to access array offset on false in <b>\/home\/benelux\/public_html\/wp-content\/themes\/franklincovey\/blocks\/block-cta-hero.php<\/b> on line <b>123<\/b><br \/>\n\u00a0\u00bb\n\t\t\t\talt=\u00a0\u00bb<br \/>\n<b>Warning<\/b>:  Trying to access array offset on false in <b>\/home\/benelux\/public_html\/wp-content\/themes\/franklincovey\/blocks\/block-cta-hero.php<\/b> on line <b>124<\/b><br \/>\n\u00a0\u00bb\n\t\t\t\twidth=\u00a0\u00bb<br \/>\n<b>Warning<\/b>:  Trying to access array offset on false in <b>\/home\/benelux\/public_html\/wp-content\/themes\/franklincovey\/blocks\/block-cta-hero.php<\/b> on line <b>125<\/b><br \/>\n\u00a0\u00bb height=\u00a0\u00bb<br \/>\n<b>Warning<\/b>:  Trying to access array offset on false in <b>\/home\/benelux\/public_html\/wp-content\/themes\/franklincovey\/blocks\/block-cta-hero.php<\/b> on line <b>125<\/b><br \/>\n\u00a0\u00bb\n\t\t\t\tclass=\u00a0\u00bbimage-main lazy\u00a0\u00bb>\n\t\t<\/div>\n\t<\/div>\n\t<span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-franklincovey-general-terms-and-conditions-of-sale-for-in-company-programs\">FranklinCovey General Terms and Conditions of Sale for In-Company Programs<\/h2>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_6a6912abd6a384f980b3180b0a2251ef\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2><h2 class=\"animated\">CONDITIONS D\u2019UTILISATION<\/h2>\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Le pr\u00e9sent site est d\u00e9tenu et exploit\u00e9 par Franklin Covey Co. (\u00ab\u00a0Franklin Covey\u00a0\u00bb). Les pr\u00e9sentes conditions d\u2019utilisation s\u2019appliquent \u00e0 l\u2019utilisation par vous et tout utilisateur autoris\u00e9 de votre compte du pr\u00e9sent site, y compris tous les services qui y sont fournis et les forums Franklin Covey (le \u00ab\u00a0site\u00a0\u00bb) et la r\u00e9gissent. Votre utilisation du pr\u00e9sent site signifie que vous acceptez d\u2019\u00eatre li\u00e9 par les pr\u00e9sentes conditions d\u2019utilisation. Si vous n\u2019acceptez pas d\u2019\u00eatre li\u00e9 par les pr\u00e9sentes conditions d\u2019utilisation, veuillez ne pas acc\u00e9der ni utiliser le pr\u00e9sent site.<\/p>\n<p>Franklin Covey se r\u00e9serve le droit, \u00e0 sa seule discr\u00e9tion, de changer, de modifier, d\u2019ajouter et de supprimer toute partie du pr\u00e9sent site ou des pr\u00e9sentes conditions d\u2019utilisation, en tout ou en partie, \u00e0 tout moment. Les changements apport\u00e9s aux pr\u00e9sentes conditions d\u2019utilisation entreront en vigueur d\u00e8s leur publication. Vous acceptez de consulter p\u00e9riodiquement les pr\u00e9sentes conditions d\u2019utilisation afin de prendre connaissance de tout changement. Votre utilisation continue du pr\u00e9sent site apr\u00e8s la publication de toute modification des conditions d\u2019utilisation sera consid\u00e9r\u00e9e comme une acceptation de ces modifications. Avant d\u2019utiliser le pr\u00e9sent site, veuillez consulter la politique de confidentialit\u00e9 de Franklin Covey. En outre, lorsque vous utilisez des services particuliers appartenant \u00e0 Franklin Covey ou exploit\u00e9s par Franklin Covey, vous \u00eates soumis \u00e0 toutes les directives ou r\u00e8gles affich\u00e9es applicables \u00e0 ces services. Toutes ces directives ou r\u00e8gles sont par la pr\u00e9sente incorpor\u00e9es par r\u00e9f\u00e9rence dans les pr\u00e9sentes conditions d\u2019utilisation.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_1ae14d92d9b5f27b15593e53329bc465\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>1. UTILISATION DU SITE\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Franklin Covey vous accorde un droit non exclusif, non transf\u00e9rable et limit\u00e9 d\u2019acc\u00e9der, d\u2019utiliser et d\u2019afficher le pr\u00e9sent site et les documents qui s\u2019y trouvent pour votre usage personnel uniquement, \u00e0 condition que vous vous conformiez enti\u00e8rement aux pr\u00e9sentes conditions d\u2019utilisation. Franklin Covey ne filtre pas le contenu fourni par les utilisateurs du site. Nonobstant ce qui pr\u00e9c\u00e8de, Franklin Covey se r\u00e9serve le droit de surveiller le contenu du site et de le supprimer \u00e0 sa seule discr\u00e9tion.<\/p>\n<p>Vous acceptez ce qui suit en ce qui concerne votre utilisation du site et des services de Franklin Covey qui y sont offerts\u00a0:<\/p>\n<ul>\n<li>\u00c0 moins que vous ne participiez \u00e0 une zone du site qui exige ou encourage l\u2019anonymat, utilisez votre vrai nom dans les communications en ligne.<\/li>\n<li>Vous ne pouvez pas afficher ou transmettre un message qui est diffamatoire ou qui divulgue des questions priv\u00e9es ou personnelles concernant une personne. Vous ne pouvez pas publier ou transmettre un message, des donn\u00e9es, une image ou un programme qui peuvent \u00eatre consid\u00e9r\u00e9s comme ind\u00e9cents, obsc\u00e8nes ou pornographiques.<\/li>\n<li>Vous ne pouvez pas afficher ou transmettre un message, des donn\u00e9es, une image ou un programme qui violerait les droits de propri\u00e9t\u00e9 d\u2019autrui, y compris des textes, des images ou des programmes non autoris\u00e9s prot\u00e9g\u00e9s par des droits d\u2019auteur, des secrets commerciaux ou d\u2019autres informations confidentielles exclusives, ainsi que des marques commerciales ou des marques de service utilis\u00e9es de mani\u00e8re illicite.<\/li>\n<li>Vous ne devez pas interf\u00e9rer avec l\u2019utilisation du site par d\u2019autres utilisateurs.<\/li>\n<li>Vous ne pouvez pas afficher ou transmettre un fichier qui contient des virus, des vers, des \u00ab\u00a0chevaux de Troie\u00a0\u00bb ou toute autre caract\u00e9ristique pouvant infecter ou d\u00e9truire du contenu.<\/li>\n<li>L\u2019intention du site n\u2019est pas de vous d\u00e9courager d\u2019adopter des positions controvers\u00e9es ou d\u2019exprimer vigoureusement ce qui peut \u00eatre des opinions impopulaires. Toutefois, vous ne pouvez pas afficher ou transmettre des messages nuisibles, mena\u00e7ants, abusifs ou haineux.<\/li>\n<li>Vous ne pouvez pas publier ou transmettre des demandes de dons, des p\u00e9titions pour des signatures, des cha\u00eenes de lettres ou des lettres relatives \u00e0 de la fraude pyramidale. Vous ne pouvez pas publier ou transmettre du contenu publicitaire, du mat\u00e9riel promotionnel ou tout autre contenu de sollicitation \u00e0 d\u2019autres utilisateurs du site pour des biens ou des services, sauf dans les zones (par exemple, un tableau d\u2019affichage de petites annonces), le cas \u00e9ch\u00e9ant, qui sont d\u00e9sign\u00e9es \u00e0 cette fin.<\/li>\n<li>Vous n\u2019\u00eates pas autoris\u00e9 \u00e0 \u00e9crire ou \u00e0 envoyer des courriels de masse non sollicit\u00e9s \u00e0 10\u00a0personnes ou plus si un tel courriel peut raisonnablement provoquer des plaintes de la part de ses destinataires.<\/li>\n<li>Vous ne pouvez pas utiliser les installations et les capacit\u00e9s du service pour mener une activit\u00e9 ou solliciter l\u2019ex\u00e9cution d\u2019une activit\u00e9 ill\u00e9gale ou d\u2019une autre activit\u00e9 qui enfreint les droits d\u2019autrui.<\/li>\n<li>Vous ne pouvez pas modifier, copier, distribuer, transmettre, afficher, ex\u00e9cuter, reproduire, publier, transf\u00e9rer ou vendre les informations, logiciels, produits ou services obtenus sur le site d\u2019une mani\u00e8re qui n\u2019est pas express\u00e9ment autoris\u00e9e par les pr\u00e9sentes et vous ne pouvez pas accorder une licence ni cr\u00e9er des \u0153uvres d\u00e9riv\u00e9es en lien avec ceux-ci.<\/li>\n<li>Franklin Covey contr\u00f4le l\u2019exploitation de ce site \u00e0 partir de son si\u00e8ge social \u00e0 Salt Lake City, Utah, aux \u00c9tats-Unis, et ne fait aucune repr\u00e9sentation que le mat\u00e9riel est appropri\u00e9 ou disponible pour une utilisation dans d\u2019autres endroits. Si vous utilisez ce site \u00e0 partir d\u2019autres endroits, vous \u00eates responsable du respect des lois locales applicables.<\/li>\n<\/ul>\n<p>Franklin Covey se r\u00e9serve le droit de prendre les mesures qu\u2019elle juge appropri\u00e9es lorsque le site est utilis\u00e9 pour diffuser des images, du texte ou d\u2019autres informations ou m\u00e9dias que Franklin Covey juge en violation des pr\u00e9sentes conditions d\u2019utilisation.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_409366c991139719d839a527a3cbc894\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>2. UTILISATION PAR LES MINEURS\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Le site est destin\u00e9 \u00e0 \u00eatre utilis\u00e9 par des adultes uniquement. En ce qui concerne le site, Franklin Covey ne fait pas de promotion en ligne aupr\u00e8s des enfants et ne recueille pas intentionnellement de renseignements personnels d\u2019enfants de moins de 13 ans.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_0c06940e22dbafaed92b5edaf670e532\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>3. DROIT D\u2019AUTEUR ET MARQUE DE COMMERCE\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>L\u2019ensemble du contenu du site est prot\u00e9g\u00e9 par les lois am\u00e9ricaines et internationales sur la propri\u00e9t\u00e9 intellectuelle. Ce site est la propri\u00e9t\u00e9 de Franklin Covey. \u00a9 2008 Franklin Covey Co. Tous droits r\u00e9serv\u00e9s.<\/p>\n<p>Franklin Covey et ses conc\u00e9dants de licence sont les propri\u00e9taires uniques et exclusifs, dans le monde entier, du droit d\u2019auteur et de tous les droits d\u2019auteur sur le site et les documents qu\u2019il contient, en vertu de la loi am\u00e9ricaine sur le droit d\u2019auteur et des lois et conventions internationales. Les visiteurs ne peuvent pas copier, reproduire ou transmettre tout mat\u00e9riel affich\u00e9 sur le site sans l\u2019autorisation \u00e9crite pr\u00e9alable expresse du ou des propri\u00e9taires du droit d\u2019auteur.<\/p>\n<p>\u00c0 l\u2019exception de ce qui est express\u00e9ment autoris\u00e9 dans les pr\u00e9sentes conditions d\u2019utilisation, vous acceptez que votre acc\u00e8s et votre utilisation du site se fassent dans les limites autoris\u00e9es par la loi applicable et que vous n\u2019\u00eates pas autoris\u00e9 \u00e0 dupliquer, \u00e0 reproduire, \u00e0 republier, \u00e0 distribuer ou \u00e0 t\u00e9l\u00e9charger tout mat\u00e9riel contenu sur le site, sauf accord contraire de Franklin Covey. Tous les droits non express\u00e9ment accord\u00e9s dans le pr\u00e9sent document sont r\u00e9serv\u00e9s.<\/p>\n<p>Vous pouvez imprimer et t\u00e9l\u00e9charger des parties du mat\u00e9riel du site uniquement pour votre propre usage non commercial, lorsque cela est autoris\u00e9. Vous \u00eates autoris\u00e9 \u00e0 faire : (a) une copie lisible par une machine, (b) une copie de sauvegarde et (c) une copie d\u2019impression de toute partie du mat\u00e9riel t\u00e9l\u00e9charg\u00e9 \u00e0 partir du site uniquement pour votre usage non commercial. Toute autre copie, redistribution, retransmission ou publication de tout mat\u00e9riel du site est strictement interdite sans le consentement \u00e9crit expr\u00e8s de Franklin Covey (voir la section Utilisation du mat\u00e9riel de Franklin Covey inclus ci-dessous) ou de tout fournisseur d\u2019information tiers au site. Vous acceptez de ne pas modifier ou supprimer les avis de propri\u00e9t\u00e9 du mat\u00e9riel t\u00e9l\u00e9charg\u00e9 \u00e0 partir du site.<\/p>\n<p>Le nom et le logo Franklin Covey, ainsi que toutes les marques et tous les slogans relatifs aux produits et services sont des marques de service et des marques de commerce de Franklin Covey. Toutes les autres marques de produits et de services contenues sur le site sont des marques de commerce de leurs propri\u00e9taires respectifs. Vous ne pouvez utiliser aucune marque de commerce, aucune marque de service ni aucun logo de Franklin Covey ou d\u2019un tiers sans le consentement \u00e9crit pr\u00e9alable de Franklin Covey ou du propri\u00e9taire de la marque de commerce du tiers.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_3d3cbad0ee19e3e28c726feaf8362748\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>4. PUBLICATIONS DES UTILISATEURS \n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Tout mat\u00e9riel, information ou autre communication que vous transmettez ou publiez sur ce site sera consid\u00e9r\u00e9 comme une communication non confidentielle et non exclusive. Franklin Covey n\u2019aura aucune obligation \u00e0 l\u2019\u00e9gard de ces communications, \u00e0 l\u2019exception de ce qui peut \u00eatre \u00e9nonc\u00e9 dans la politique de confidentialit\u00e9. Franklin Covey et ses mandataires seront libres de copier, de divulguer, de distribuer, d\u2019incorporer et d\u2019utiliser autrement les communications et toutes les donn\u00e9es et images et tous les sons, textes et autres \u00e9l\u00e9ments qui y sont incorpor\u00e9s \u00e0 toutes fins commerciales ou non commerciales. Aucune compensation ne sera vers\u00e9e en ce qui concerne l\u2019utilisation de votre publication. Franklin Covey n\u2019a aucune obligation de publier ou d\u2019utiliser toute publication que vous pouvez fournir et Franklin Covey peut retirer toute publication \u00e0 tout moment \u00e0 sa seule discr\u00e9tion.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_ba9100fcb815f2b07d2bab9514e94750\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>5. EXCLUSION DE GARANTIES\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Vous comprenez que Franklin Covey ne peut pas garantir ni certifier que les fichiers disponibles pour t\u00e9l\u00e9chargement par le site seront exempts d\u2019infection ou de virus, de vers, de chevaux de Troie ou d\u2019autres codes qui manifestent des propri\u00e9t\u00e9s permettant de d\u00e9truire ou d\u2019infecter le contenu. Vous \u00eates responsable de la mise en \u0153uvre de mesures de sauvegarde suffisantes pour satisfaire vos exigences particuli\u00e8res en mati\u00e8re d\u2019exactitude de l\u2019entr\u00e9e et de la sortie des donn\u00e9es, et du maintien d\u2019un moyen externe au site pour la reconstruction de toute donn\u00e9e perdue. Vous assumez l\u2019enti\u00e8re responsabilit\u00e9 et le risque de votre utilisation du site et de l\u2019Internet.<\/p>\n<p>LE SITE EST FOURNI \u00ab EN L\u2019\u00c9TAT \u00bb SANS AUCUNE GARANTIE DE QUELQUE NATURE QUE CE SOIT. TOUTES LES GARANTIES EXPRESSES, IMPLICITES ET L\u00c9GALES, Y COMPRIS, SANS LIMITATION, LES GARANTIES DE QUALIT\u00c9 MARCHANDE, D\u2019AD\u00c9QUATION \u00c0 UN USAGE PARTICULIER ET DE NON-VIOLATION, SONT EXPRESS\u00c9MENT REJET\u00c9ES. DANS TOUTE LA MESURE PERMISE PAR LA LOI, FRANKLIN COVEY D\u00c9CLINE TOUTE GARANTIE SELON LAQUELLE LE SITE OU LA MARCHANDISE, L\u2019INFORMATION OU LES SERVICES FOURNIS AU MOYEN DU SITE SONT EXEMPTS DE D\u00c9FAUTS OU DE VIRUS ET D\u00c9CLINE TOUTE GARANTIE QUANT \u00c0 LA S\u00c9CURIT\u00c9, L\u2019EXACTITUDE, LA FIABILIT\u00c9, LA TRANSMISSION EN TEMPS UTILE ET LA PERFORMANCE. VOTRE UTILISATION DE CE SITE WEB SE FAIT UNIQUEMENT \u00c0 VOS PROPRES RISQUES.<\/p>\n<p>VOUS COMPRENEZ ET ACCEPTEZ QUE LA SOUMISSION DE TOUT CONTENU NUM\u00c9RIQUE \u00c0 FRANKLIN COVEY SE FAIT \u00c0 VOTRE PROPRE DISCR\u00c9TION ET \u00c0 VOS PROPRES RISQUES ET QUE VOUS SEREZ SEUL RESPONSABLE DE TOUTE PERTE OU DE TOUT DOMMAGE Y AFF\u00c9RENT.<\/p>\n<p>Il est de votre seule responsabilit\u00e9 d\u2019\u00e9valuer l\u2019exactitude, l\u2019exhaustivit\u00e9 et l\u2019utilit\u00e9 de toute opinion, marchandise et information ainsi que tout conseil et service fournis par le site ou sur Internet en g\u00e9n\u00e9ral. Franklin Covey ne garantit pas que le site sera ininterrompu ou sans erreur ou que les d\u00e9fauts du site seront corrig\u00e9s. Le site et tout logiciel rendu disponible sur le site sont fournis sur une base \u00ab en l\u2019\u00e9tat, tel que disponible \u00bb. Les documents et les graphiques connexes publi\u00e9s sur ce site peuvent comporter des inexactitudes techniques ou des erreurs typographiques. Des modifications sont apport\u00e9es p\u00e9riodiquement aux informations contenues dans le pr\u00e9sent document. Franklin Covey ou ses fournisseurs respectifs peuvent apporter des am\u00e9liorations et des changements aux produits ou aux programmes d\u00e9crits ici \u00e0 tout moment.<\/p>\n<p>Certains liens sur ce site peuvent vous faire quitter le site de Franklin Covey. Les sites li\u00e9s ne sont pas sous le contr\u00f4le de Franklin Covey et Franklin Covey n\u2019est pas responsable du contenu du site li\u00e9, de tout site li\u00e9 contenu dans un site li\u00e9, ni de tout changement ni mise \u00e0 jour de ces sites. Franklin Covey vous fournit des liens uniquement \u00e0 titre de commodit\u00e9, et l\u2019inclusion de tout lien n\u2019implique pas l\u2019approbation du site par Franklin Covey. Vous comprenez en outre que l\u2019Internet contient des contenus non \u00e9dit\u00e9s pouvant parfois \u00eatre sexuellement explicites ou offensants pour vous. Vous acc\u00e9dez \u00e0 ces contenus \u00e0 vos risques et p\u00e9rils. Franklin Covey n\u2019exerce aucun contr\u00f4le sur de tels contenus et n\u2019en accepte aucunement la responsabilit\u00e9.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_67ac7cbb38868e7d95ac54724613dd2c\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>6. RESPONSABILIT\u00c9 LIMIT\u00c9E\/DOMMAGES \n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>EN AUCUN CAS, Y COMPRIS, MAIS SANS S\u2019Y LIMITER, LA N\u00c9GLIGENCE, FRANKLIN COVEY NE SERA RESPONSABLE DE TOUTE R\u00c9CLAMATION, TOUTE RESPONSABILIT\u00c9, TOUTE D\u00c9PENSE OU TOUT DOMMAGE (QU\u2019IL SOIT R\u00c9EL, INDIRECT, SP\u00c9CIAL, EXEMPLAIRE OU CONS\u00c9CUTIF) LI\u00c9 AUX INFORMATIONS FIGURANT SUR LE SITE OU LORS DE L\u2019UTILISATION DU SITE, OU \u00c0 L\u2019INCAPACIT\u00c9 D\u2019UTILISER, LE SITE, LES MAT\u00c9RIAUX DU SITE OU LE LOGICIEL, M\u00caME SI FRANKLIN COVEY A \u00c9T\u00c9 INFORM\u00c9E DE LA POSSIBILIT\u00c9 DE TELS DOMMAGES.<\/p>\n<p>FRANKLIN COVEY D\u00c9CLINE TOUTE RESPONSABILIT\u00c9 POUR LES ACTES, LES OMISSIONS ET LA CONDUITE DE TOUT UTILISATEUR ET DE TOUT ANNONCEUR OU COMMANDITAIRE SUR LE SITE. VOUS ACCEPTEZ QUE FRANKLIN COVEY NE SOIT PAS RESPONSABLE DE TOUTE PERTE OU DE TOUT DOMMAGE DE QUELQUE NATURE QUE CE SOIT R\u00c9SULTANT DE TOUTE TRANSACTION AVEC DES ANNONCEURS TROUV\u00c9S SUR OU PAR LE SITE WEB, OU R\u00c9SULTANT DE LA PR\u00c9SENCE DE TELS ANNONCEURS SUR LE SITE WEB.<\/p>\n<p>LA LOI APPLICABLE PEUT NE PAS AUTORISER LA LIMITATION OU L\u2019EXCLUSION DE LA RESPONSABILIT\u00c9 OU DES DOMMAGES EXEMPLAIRES, ACCESSOIRES OU CONS\u00c9CUTIFS, DE SORTE QUE LA LIMITATION OU L\u2019EXCLUSION CI-DESSUS PEUT NE PAS S\u2019APPLIQUER \u00c0 VOUS. EN AUCUN CAS, LA RESPONSABILIT\u00c9 TOTALE DE FRANKLIN COVEY ENVERS VOUS POUR TOUS LES DOMMAGES, PERTES ET CAUSES D\u2019ACTION (QUE CE SOIT DANS LE CADRE D\u2019UN CONTRAT, D\u2019UN D\u00c9LIT CIVIL, Y COMPRIS, MAIS SANS S\u2019Y LIMITER, LA N\u00c9GLIGENCE, OU AUTREMENT) NE D\u00c9PASSERA LE MONTANT QUE VOUS AVEZ PAY\u00c9, LE CAS \u00c9CH\u00c9ANT, POUR ACC\u00c9DER \u00c0 CE SITE OU UTILISER LES SERVICES OFFERTS SUR LE SITE. COMME CERTAINS \u00c9TATS N\u2019AUTORISENT PAS L\u2019EXCLUSION OU LA LIMITATION DE LA RESPONSABILIT\u00c9 POUR LES DOMMAGES CONS\u00c9CUTIFS OU ACCESSOIRES, LA LIMITATION CI-DESSUS PEUT NE PAS S\u2019APPLIQUER \u00c0 VOUS. DANS DE TELS \u00c9TATS, LA RESPONSABILIT\u00c9 DE FRANKLIN COVEY EST LIMIT\u00c9E DANS LA PLUS GRANDE MESURE PERMISE PAR LA LOI.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_cdac3c0dac74f370da0f92c9cc3f20c5\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>7. AVIS SP\u00c9CIFIQUE POUR LES LOGICIELS DISPONIBLES SUR CE SITE WEB\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Tout logiciel mis \u00e0 disposition pour \u00eatre utilis\u00e9 ou t\u00e9l\u00e9charg\u00e9 \u00e0 partir de ce site (\u00ab Logiciel \u00bb) est prot\u00e9g\u00e9 par les lois applicables sur la propri\u00e9t\u00e9 intellectuelle, y compris les lois am\u00e9ricaines et internationales sur le droit d\u2019auteur, et est la propri\u00e9t\u00e9 de Franklin Covey ou de ses fournisseurs. L\u2019utilisation du logiciel est r\u00e9gie par les termes du contrat de licence de l\u2019utilisateur final qui accompagne le logiciel ou y est inclus (\u00ab Convention des droits d\u2019utilisation \u00bb).<\/p>\n<p>Le logiciel est mis \u00e0 disposition pour \u00eatre t\u00e9l\u00e9charg\u00e9 uniquement pour \u00eatre utilis\u00e9 par les utilisateurs finaux conform\u00e9ment \u00e0 la Convention des droits d\u2019utilisation. Toute copie, reproduction ou redistribution du logiciel non conforme \u00e0 la Convention des droits d\u2019utilisation est express\u00e9ment interdite. Le logiciel et les autres produits technologiques sont garantis, le cas \u00e9ch\u00e9ant, uniquement selon les termes de la Convention des droits d\u2019utilisation. \u00c0 L\u2019EXCEPTION DE CE QUI EST GARANTI DANS LA CONVENTION DES DROITS D\u2019UTILISATION, FRANKLIN COVEY ET SES AFFILI\u00c9S REJETTENT PAR LA PR\u00c9SENTE TOUTES LES GARANTIES ET CONDITIONS RELATIVES AU LOGICIEL ET AUX AUTRES PRODUITS TECHNOLOGIQUES, Y COMPRIS TOUTES LES GARANTIES ET CONDITIONS IMPLICITES DE QUALIT\u00c9 MARCHANDE, D\u2019AD\u00c9QUATION \u00c0 UN USAGE PARTICULIER, DE TITRE ET DE NON-VIOLATION.<\/p>\n<p>Tout logiciel t\u00e9l\u00e9charg\u00e9 \u00e0 partir de ce site pour les \u00c9tats-Unis d\u2019Am\u00e9rique ou en leur nom, de leurs agences ou instruments (\u00ab Gouvernement am\u00e9ricain \u00bb), est fourni avec des droits restreints. Utilisation, duplication ou divulgation par les \u00c9tats-Unis. Le gouvernement est soumis aux restrictions \u00e9nonc\u00e9es au sous-alin\u00e9a (c)(1)(ii) de la clause Droits sur les donn\u00e9es techniques et les logiciels informatiques du DFARS 252.227-7013 ou aux sous-alin\u00e9as (c)(1) et (2) de la clause Logiciels commerciaux \u2013 Droits restreints du 48 CFR 52.227-19, selon le cas. Certains logiciels de ce site peuvent \u00eatre soumis \u00e0 des contr\u00f4les d\u2019exportation ou de r\u00e9exportation impos\u00e9s par les \u00c9tats-Unis et ne peuvent \u00eatre t\u00e9l\u00e9charg\u00e9s ou autrement export\u00e9s ou r\u00e9export\u00e9s : a) dans (ou \u00e0 un ressortissant ou r\u00e9sident de) tout pays \u00e0 l\u2019\u00e9gard duquel les \u00c9tats-Unis ont plac\u00e9 un embargo, y compris, sans s\u2019y limiter, Cuba, l\u2019Iran, l\u2019Irak, la Libye, la Cor\u00e9e du Nord ou la Syrie; (b) \u00e0 toute personne figurant sur la liste des ressortissants sp\u00e9cialement d\u00e9sign\u00e9s du d\u00e9partement du Tr\u00e9sor des \u00c9tats-Unis, ou (c) \u00e0 toute personne figurant au tableau des ordonnances de refus du d\u00e9partement du Commerce des \u00c9tats-Unis. Si vous t\u00e9l\u00e9chargez ou utilisez le logiciel, vous d\u00e9clarez et garantissez que vous n\u2019\u00eates pas situ\u00e9 dans un tel pays ou sur une telle liste, que vous n\u2019\u00eates pas sous son contr\u00f4le ou que vous n\u2019en \u00eates pas un ressortissant.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_7e438d1555de2536048e2062d5ea8f4b\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>8. INDEMNISATION\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <div class=\"intro-text\">\n<p>Vous acceptez d\u2019indemniser et de d\u00e9fendre Franklin Covey et ses responsables, directeurs, employ\u00e9s, agents, conc\u00e9dants, fournisseurs et fournisseurs tiers de renseignements contre toute perte, tout frais, tout dommage et tout co\u00fbt, y compris des frais d\u2019avocats raisonnables, d\u00e9coulant de toute infraction de votre part \u00e0 la pr\u00e9sente entente.<\/p>\n<p>Les dispositions de ces conditions d\u2019utilisation sont \u00e9tablies au profit de Franklin Covey et de ses responsables, directeurs, employ\u00e9s, agents, conc\u00e9dants, fournisseurs et fournisseurs tiers de renseignements pour son site. Chacune de ces personnes ou entit\u00e9s a le droit de faire appliquer ces dispositions envers vous en leur propre nom.<\/p>\n<\/div>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_463c77a3cc8043cbc7579e0ad842e583\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>9. CESSATION\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Vous comprenez et acceptez que Franklin Covey peut, \u00e0 sa seule discr\u00e9tion et en tout temps, mettre fin \u00e0 votre nom d\u2019utilisateur et votre mot de passe, \u00e0 tout compte cr\u00e9\u00e9 sur le site ou \u00e0 l\u2019utilisation de tout et supprimer, et ce pour quelque raison que ce soit, tout contenu que vous avez publi\u00e9 ou soumis sur tout forum. Franklin Covey peut \u00e9galement, en tout temps et \u00e0 sa seule discr\u00e9tion, mettre fin \u00e0 tout forum ou limiter ou restreindre l\u2019acc\u00e8s d\u2019un utilisateur \u00e0 un forum, et ce pour quelque raison que ce soit. Vous comprenez et acceptez que Franklin Covey peut effectuer ces actions sans vous aviser au pr\u00e9alable. Si Franklin Covey effectue l\u2019une de ces actions, elle peut, \u00e0 sa seule discr\u00e9tion, imm\u00e9diatement d\u00e9sactiver ou supprimer tout renseignement concernant votre compte, y compris tout renseignement fourni pour l\u2019inscription au site et tout contenu soumis. VOUS COMPRENEZ ET ACCEPTEZ QUE FRANKLIN COVEY N\u2019AURA AUCUNE RESPONSABILIT\u00c9 ENVERS VOUS OU TOUTE AUTRE PERSONNE POUR TOUTE RESTRICTION DE VOTRE ACC\u00c8S \u00c0 UN FORUM OU LA SUPPRESSION DE TOUT RENSEIGNEMENT CONCERNANT VOTRE COMPTE.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_cb37c297e73c2fadc66cbfe598e5a575\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>10. INFRACTION AU DROIT D\u2019AUTEUR OU \u00c0 LA PROPRI\u00c9T\u00c9 INTELLECTUELLE\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Franklin Covey respecte la propri\u00e9t\u00e9 intellectuelle des autres et demande \u00e0 ces utilisateurs d\u2019en faire autant. Franklin Covey peut, \u00e0 sa discr\u00e9tion, si les circonstances sont appropri\u00e9es, d\u00e9sactiver ou supprimer le compte d\u2019utilisateurs pouvant avoir commis des infractions \u00e0 ces droits \u00e0 plusieurs reprises.<\/p>\n<p>Si vous croyez que du contenu vous appartenant a \u00e9t\u00e9 mis \u00e0 disposition sur le site d\u2019une mani\u00e8re constituant une infraction au droit d\u2019auteur, ou si vos droits de propri\u00e9t\u00e9 intellectuelle ont \u00e9t\u00e9 autrement enfreints en lien avec le site, veuillez fournir les renseignements suivants au responsable des droits d\u2019auteur de Franklin Covey\u00a0:<\/p>\n<p>(1) Une signature \u00e9lectronique ou physique de la personne autoris\u00e9e \u00e0 agir au nom du d\u00e9tenteur du droit d\u2019auteur ou de l\u2019int\u00e9r\u00eat de propri\u00e9t\u00e9 intellectuelle;<br \/>\n(2) une description du contenu sous droit d\u2019auteur ou de la propri\u00e9t\u00e9 intellectuelle que vous croyez \u00eatre utilis\u00e9s de mani\u00e8re illicite;<br \/>\n(3) une description de l\u2019endroit au sein du service o\u00f9 se trouve le contenu que vous croyez \u00eatre utilis\u00e9 de mani\u00e8re illicite;<br \/>\n(4) votre adresse, votre num\u00e9ro de t\u00e9l\u00e9phone et votre adresse courriel;<br \/>\n(5) une d\u00e9claration de votre part affirmant que vous croyez de bonne foi que l\u2019utilisation signal\u00e9e n\u2019a pas \u00e9t\u00e9 autoris\u00e9e par le d\u00e9tenteur du droit d\u2019auteur ou de la propri\u00e9t\u00e9 intellectuelle, son repr\u00e9sentant ou la loi; et<br \/>\n(6) une d\u00e9claration de votre part, sous peine de parjure, que les renseignements ci-dessus inclus dans votre signalement sont exacts et que vous \u00eates le d\u00e9tenteur du droit d\u2019auteur ou de la propri\u00e9t\u00e9 intellectuelle, ou autoris\u00e9 \u00e0 agir pour le compte du d\u00e9tenteur du droit d\u2019auteur ou de la propri\u00e9t\u00e9 intellectuelle.<\/p>\n<p>Vous pouvez communiquer avec le responsable du signalement des infractions au droit d\u2019auteur ou de propri\u00e9t\u00e9 intellectuelle de Franklin Covey aux coordonn\u00e9es suivantes\u00a0:<\/p>\n<p>Agent for Notice of Claims<br \/>\nFranklin Covey Co.<br \/>\n2200 West Parkway Blvd. MS 0213<br \/>\nSalt Lake City, UT 84119<br \/>\nFax: (801) 817-8197<br \/>\nCourriel\u00a0:\u00a0<a href=\"mailto:legal@franklincovey.com\">legal@franklincovey.com<\/a><\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_45e5cc591f3e80eb89dd157e4cdccc1a\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>11. IDENTIFIANT DE CONNEXION UNIQUE POUR LES UTILISATEURS D\u2019ALL ACCESS PASS\u00ae DE Franklin Covey \n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Par d\u00e9faut, All Access Pass<sup><sup>&reg;<\/sup><\/sup> (\u00ab\u00a0AAP\u00a0\u00bb) n\u00e9cessite un identifiant d\u2019utilisateur unique et un mot de passe pour l\u2019authentification. L\u2019application est configur\u00e9e pour exiger des param\u00e8tres de complexit\u00e9 et une longueur minimale de mot de passe.\u00a0Franklin Covey fournit \u00e9galement une configuration d\u2019identifiant de connexion unique \u00e0 gestion centrale pouvant int\u00e9grer AAP \u00e0 des solutions d\u2019identifiant de connexion unique d\u2019entreprise existantes, y compris des solutions f\u00e9d\u00e9r\u00e9es prenant en charge la technologie Security Assertion Markup Language (SAML) 2.0. La configuration d\u2019une authentification SAML permet \u00e9galement au client de mettre en place une authentification \u00e0 deux facteurs. Lorsque la connectivit\u00e9 SAML est activ\u00e9e, l\u2019authentification des utilisateurs est contr\u00f4l\u00e9e par le syst\u00e8me d\u2019identifiant de connexion unique du client et la responsabilit\u00e9 pour la complexit\u00e9 et la longueur des mots de passe incombe alors uniquement au syst\u00e8me d\u2019identifiant de connexion unique du client.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_400043deccc2cd9e5d354297bf1b30c7\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>12. DIVERS\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Les pr\u00e9sentes modalit\u00e9s d\u2019utilisation sont r\u00e9gies et interpr\u00e9t\u00e9es conform\u00e9ment aux lois de l\u2019\u00c9tat de l\u2019Utah et des \u00c9tats-Unis, nonobstant les principes de conflits des lois. Vous acceptez que toute action intent\u00e9e relativement aux pr\u00e9sentes sera entendue devant les tribunaux \u00e9tatiques ou f\u00e9d\u00e9raux situ\u00e9s \u00e0 Salt Lake City, Utah, et acceptez par les pr\u00e9sentes la juridiction personnelle de ces tribunaux pour toute action en lien avec l\u2019utilisation du site ou la pr\u00e9sente entente ou d\u00e9coulant de l\u2019utilisation du site ou de la pr\u00e9sente entente. Vous n\u2019avez en aucun cas droit \u00e0 une mesure injonctive ou \u00e0 toute autre mesure \u00e9quitable. Si une disposition des pr\u00e9sentes modalit\u00e9s s\u2019av\u00e8re ill\u00e9gale, nulle ou inapplicable pour quelque raison que ce soit, cette disposition sera consid\u00e9r\u00e9e comme s\u00e9parable des pr\u00e9sentes modalit\u00e9s et n\u2019aura aucune incidence sur la validit\u00e9 ou le caract\u00e8re ex\u00e9cutoire des autres dispositions.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<div style=\"height:130px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-b-utilisation-du-materiel-de-franklin-covey\">B. Utilisation du mat\u00e9riel de Franklin Covey<\/h2>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<span class=\"animated-line\"><\/span>\n\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_54359ac2a134efce4b01616a31c8400f\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>1. OCTROI DE LICENCES\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Des licences multiutilisateurs et d\u2019autres moyens d\u2019acheter et d\u2019utiliser du mat\u00e9riel sous droit d\u2019auteur de Franklin Covey de mani\u00e8re interne \u00e0 des fins de formation, d\u2019enseignement et de diss\u00e9mination peuvent \u00eatre obtenus en communiquant avec Franklin Covey. Pour en savoir plus sur nos proc\u00e9dures d\u2019octroi de licences, composez le 888-868-1776.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_7bb934c5d99ddbee537b00c88b7662c3\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>2. PERMISSION\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Si vous d\u00e9sirez utiliser du mat\u00e9riel de Franklin Covey \u00e0 des fins non personnelles de mani\u00e8re limit\u00e9e, vous devez remplir et soumettre un formulaire de demande de permission. Franklin Covey \u00e9tudie chaque demande au cas par cas et peut d\u00e9cider d\u2019approuver ou de refuser votre demande \u00e0 sa seule discr\u00e9tion. Veuillez pr\u00e9voir un d\u00e9lai de 4 \u00e0 6 semaines pour le traitement de votre demande.<\/p>\n<p>Si vous nous faites parvenir votre demande par courriel depuis l\u2019ext\u00e9rieur des \u00c9tats-Unis, veuillez indiquer qu\u2019il s\u2019agit d\u2019une demande de permission internationale dans l\u2019objet de votre courriel pour nous aider \u00e0 acheminer votre demande \u00e0 la bonne personne.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_3f58447199e3b1f173660aac7bf66f74\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>C. Autres renseignements \n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                                        \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_f9ec117762891ace5bea917a2f28629f\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>1. SUGGESTIONS, R\u00c9TROACTION ET ID\u00c9ES DE PRODUITS NON SOLLICIT\u00c9ES\n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Les suggestions, r\u00e9troactions et id\u00e9es de produits non sollicit\u00e9es soumises \u00e0 Franklin Covey ne sont pas confidentielles. Toutes les soumissions sont assujetties \u00e0 politique sur les soumissions des utilisateurs jointe ci-dessus.<\/p>\n<p>SUGGESTIONS ET R\u00c9TROACTION NON SOLLICIT\u00c9ES : Toutes les suggestions peuvent \u00eatre soumises par courriel \u00e0 l\u2019adresse feedback@Franklin Covey.com ou par message vocal au (801) 817-4100.<\/p>\n<p>ID\u00c9ES DE PRODUITS NON SOLLICIT\u00c9ES : Franklin Covey n\u2019accepte pas de propositions pour de nouveaux produits pour le moment.<\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>\n\n\n<section class=\"block block-intro-text headings-left\" data-id=\"block_3e7d55a3f3220b26c487494b5033fc60\">\n        <div class=\"uk-flex uk-justify-sb\">\n        <div class=\"intro-headings\">\n            <h2>D. Coordonn\u00e9es \n<\/h2>\n        <\/div>\n        <div class=\"intro-text\">\n                            <p>Pour toute autre question concernant les termes employ\u00e9s dans cette page, communiquez avec les services juridiques de Franklin Covey ou l\u2019administrateur du site Web de Franklin Covey\u00a0:<\/p>\n<p>Franklin Covey Co.<br \/>\nAttn\u00a0: Director of Legal Services<br \/>\n2200 West Parkway Boulevard<br \/>\nSalt Lake City, UT 84119<\/p>\n<p>(801) 817-5635<br \/>\nT\u00e9l\u00e9copieur\u00a0: (801) 817-8197<br \/>\ncourriel:\u00a0<a href=\"mailto:legal@franklincovey.com\">legal@franklincovey.com<\/a><\/p>\n<p>Franklin Covey Webmaster<br \/>\n2200 West Parkway Boulevard<br \/>\nSalt Lake City, UT 84119<\/p>\n<p>Courriel\u00a0:\u00a0<a href=\"mailto:webmaster@franklincovey.com\">webmaster@franklincovey.com<\/a><\/p>\n            \n                    <\/div>\n    <\/div>\n    <span class=\"animated-line\"><\/span>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>FranklinCovey General Terms and Conditions of Sale for In-Company Programs B. Utilisation du mat\u00e9riel de Franklin Covey<\/p>\n","protected":false},"author":42,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"wf_page_folders":[11],"class_list":["post-21735","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Terms and Conditions | FranklinCovey<\/title>\n<meta name=\"description\" content=\"Les pr\u00e9sentes conditions d&#039;utilisation s&#039;appliquent \u00e0 l&#039;utilisation par vous et tout utilisateur autoris\u00e9 de votre compte du pr\u00e9sent site, y compris tous les services qui y sont fournis et les forums FranklinCovey (le \u00ab\u00a0site\u00a0\u00bb) et la r\u00e9gissent.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/terms-and-conditions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms (new)\" \/>\n<meta property=\"og:description\" content=\"Les pr\u00e9sentes conditions d&#039;utilisation s&#039;appliquent \u00e0 l&#039;utilisation par vous et tout utilisateur autoris\u00e9 de votre compte du pr\u00e9sent site, y compris tous les services qui y sont fournis et les forums FranklinCovey (le \u00ab\u00a0site\u00a0\u00bb) et la r\u00e9gissent.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/terms-and-conditions\/\" \/>\n<meta property=\"og:site_name\" content=\"FranklinCovey\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T10:35:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/benelux.vps.buzztestserver.co.uk\\\/fr\\\/terms-and-conditions\\\/\",\"url\":\"https:\\\/\\\/benelux.vps.buzztestserver.co.uk\\\/fr\\\/terms-and-conditions\\\/\",\"name\":\"Terms and Conditions | FranklinCovey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/benelux.vps.buzztestserver.co.uk\\\/fr\\\/#website\"},\"datePublished\":\"2023-02-13T12:28:09+00:00\",\"dateModified\":\"2024-03-08T10:35:57+00:00\",\"description\":\"Les pr\u00e9sentes conditions d'utilisation s'appliquent \u00e0 l'utilisation par vous et tout utilisateur autoris\u00e9 de votre compte du pr\u00e9sent site, y compris tous les services qui y sont fournis et les forums FranklinCovey (le \u00ab\u00a0site\u00a0\u00bb) et la r\u00e9gissent.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/benelux.vps.buzztestserver.co.uk\\\/fr\\\/terms-and-conditions\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/benelux.vps.buzztestserver.co.uk\\\/fr\\\/terms-and-conditions\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/benelux.vps.buzztestserver.co.uk\\\/fr\\\/terms-and-conditions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/benelux.vps.buzztestserver.co.uk\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms (new)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/benelux.vps.buzztestserver.co.uk\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/benelux.vps.buzztestserver.co.uk\\\/fr\\\/\",\"name\":\"FranklinCovey\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/benelux.vps.buzztestserver.co.uk\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Terms and Conditions | FranklinCovey","description":"Les pr\u00e9sentes conditions d'utilisation s'appliquent \u00e0 l'utilisation par vous et tout utilisateur autoris\u00e9 de votre compte du pr\u00e9sent site, y compris tous les services qui y sont fournis et les forums FranklinCovey (le \u00ab\u00a0site\u00a0\u00bb) et la r\u00e9gissent.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/terms-and-conditions\/","og_locale":"fr_FR","og_type":"article","og_title":"Terms (new)","og_description":"Les pr\u00e9sentes conditions d'utilisation s'appliquent \u00e0 l'utilisation par vous et tout utilisateur autoris\u00e9 de votre compte du pr\u00e9sent site, y compris tous les services qui y sont fournis et les forums FranklinCovey (le \u00ab\u00a0site\u00a0\u00bb) et la r\u00e9gissent.","og_url":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/terms-and-conditions\/","og_site_name":"FranklinCovey","article_modified_time":"2024-03-08T10:35:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/terms-and-conditions\/","url":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/terms-and-conditions\/","name":"Terms and Conditions | FranklinCovey","isPartOf":{"@id":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/#website"},"datePublished":"2023-02-13T12:28:09+00:00","dateModified":"2024-03-08T10:35:57+00:00","description":"Les pr\u00e9sentes conditions d'utilisation s'appliquent \u00e0 l'utilisation par vous et tout utilisateur autoris\u00e9 de votre compte du pr\u00e9sent site, y compris tous les services qui y sont fournis et les forums FranklinCovey (le \u00ab\u00a0site\u00a0\u00bb) et la r\u00e9gissent.","breadcrumb":{"@id":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/terms-and-conditions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/terms-and-conditions\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/terms-and-conditions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/"},{"@type":"ListItem","position":2,"name":"Terms (new)"}]},{"@type":"WebSite","@id":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/#website","url":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/","name":"FranklinCovey","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/wp-json\/wp\/v2\/pages\/21735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/wp-json\/wp\/v2\/comments?post=21735"}],"version-history":[{"count":9,"href":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/wp-json\/wp\/v2\/pages\/21735\/revisions"}],"predecessor-version":[{"id":30818,"href":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/wp-json\/wp\/v2\/pages\/21735\/revisions\/30818"}],"wp:attachment":[{"href":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/wp-json\/wp\/v2\/media?parent=21735"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/benelux.vps.buzztestserver.co.uk\/fr\/wp-json\/wp\/v2\/wf_page_folders?post=21735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}